{"id":539,"date":"2019-12-25T10:00:28","date_gmt":"2019-12-25T03:00:28","guid":{"rendered":"https:\/\/www.synphaet.co.th\/children-ramintra\/?p=539"},"modified":"2020-07-15T09:07:25","modified_gmt":"2020-07-15T02:07:25","slug":"%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b9%84%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%b5%e0%b8%94%e0%b8%b3%e0%b8%ad%e0%b8%b5%e0%b9%81%e0%b8%94%e0%b8%87","status":"publish","type":"post","link":"https:\/\/www.synphaet.co.th\/children-ramintra\/%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b9%84%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%b5%e0%b8%94%e0%b8%b3%e0%b8%ad%e0%b8%b5%e0%b9%81%e0%b8%94%e0%b8%87\/","title":{"rendered":"\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07 (Scarlet fever)"},"content":{"rendered":"<h3>\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07 (Scarlet fever)<\/h3>\n<p>\u0e42\u0e23\u0e04\u0e0a\u0e37\u0e48\u0e2d\u0e44\u0e17\u0e22\u0e46 \u0e17\u0e35\u0e48\u0e43\u0e04\u0e23\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e1e\u0e1a\u0e44\u0e14\u0e49\u0e1a\u0e48\u0e2d\u0e22\u0e43\u0e19\u0e40\u0e14\u0e47\u0e01\u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e1a\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e14\u0e49\u0e27\u0e22\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e02\u0e49 \u0e40\u0e08\u0e47\u0e1a\u0e04\u0e2d \u0e42\u0e14\u0e22\u0e08\u0e30\u0e1e\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e23\u0e48\u0e27\u0e21\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e37\u0e0d \u0e04\u0e37\u0e2d \u0e25\u0e34\u0e49\u0e19\u0e1a\u0e27\u0e21\u0e41\u0e14\u0e07\u0e04\u0e25\u0e49\u0e32\u0e22\u0e1c\u0e25\u0e2a\u0e15\u0e23\u0e2d\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e23\u0e35\u0e48 (Strawberry tongue) \u0e41\u0e25\u0e30\u0e21\u0e35\u0e1c\u0e37\u0e48\u0e19\u0e41\u0e14\u0e07\u0e02\u0e36\u0e49\u0e19\u0e15\u0e32\u0e21\u0e15\u0e31\u0e27 \u0e1c\u0e37\u0e48\u0e19\u0e08\u0e30\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e04\u0e37\u0e2d\u0e04\u0e25\u0e33\u0e41\u0e25\u0e49\u0e27\u0e2a\u0e32\u0e01\u0e04\u0e25\u0e49\u0e32\u0e22\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e17\u0e23\u0e32\u0e22 (Sand paper like rash) \u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e20\u0e32\u0e22\u0e43\u0e19 1-2 \u0e27\u0e31\u0e19 \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e40\u0e23\u0e34\u0e48\u0e21\u0e21\u0e35\u0e44\u0e02\u0e49 \u0e1e\u0e1a\u0e21\u0e32\u0e01\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e25\u0e33\u0e15\u0e31\u0e27\u0e41\u0e25\u0e49\u0e27\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e41\u0e02\u0e19\u0e02\u0e32 \u0e21\u0e31\u0e01\u0e44\u0e21\u0e48\u0e1e\u0e1a\u0e1c\u0e37\u0e48\u0e19\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e43\u0e1a\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e15\u0e48\u0e1e\u0e1a\u0e41\u0e01\u0e49\u0e21\u0e41\u0e14\u0e07 \u0e21\u0e35\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e0b\u0e35\u0e14\u0e23\u0e2d\u0e1a\u0e1b\u0e32\u0e01 \u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e02\u0e49\u0e2d\u0e1e\u0e31\u0e1a\u0e41\u0e02\u0e19 2 \u0e02\u0e49\u0e32\u0e07 \u0e21\u0e35\u0e2a\u0e35\u0e40\u0e02\u0e49\u0e21\u0e04\u0e25\u0e49\u0e33\u0e01\u0e27\u0e48\u0e32\u0e1b\u0e01\u0e15\u0e34 \u0e1c\u0e37\u0e48\u0e19\u0e08\u0e30\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 3 &#8211; 4 \u0e27\u0e31\u0e19 \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e1c\u0e37\u0e48\u0e19\u0e08\u0e30\u0e25\u0e2d\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e38\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e1c\u0e48\u0e19\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e1c\u0e34\u0e27\u0e2b\u0e19\u0e31\u0e07\u0e44\u0e25\u0e48\u0e08\u0e32\u0e01\u0e43\u0e1a\u0e2b\u0e19\u0e49\u0e32 \u0e25\u0e33\u0e04\u0e2d \u0e25\u0e33\u0e15\u0e31\u0e27\u0e08\u0e19\u0e16\u0e36\u0e07\u0e1b\u0e25\u0e32\u0e22\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e17\u0e49\u0e32<\/p>\n<p>&nbsp;<\/p>\n<p>\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e41\u0e1a\u0e04\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22 \u0e0a\u0e37\u0e48\u0e2d \u0e2a\u0e40\u0e15\u0e23\u0e1b\u0e42\u0e15\u0e04\u0e2d\u0e04\u0e04\u0e31\u0e2a\u0e0a\u0e19\u0e34\u0e14\u0e40\u0e2d (Streptococcus group A) \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e16\u0e34\u0e48\u0e19 \u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e04\u0e2d\u0e2b\u0e2d\u0e22\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e02\u0e2d\u0e07\u0e04\u0e2d\u0e2b\u0e2d\u0e22\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e21\u0e17\u0e2d\u0e19\u0e0b\u0e34\u0e25 \u0e1e\u0e1a\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e2d\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e38\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e14\u0e2d\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e04\u0e2d\u0e2b\u0e2d\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e48\u0e2d\u0e21\u0e17\u0e2d\u0e19\u0e0b\u0e34\u0e25 \u0e42\u0e14\u0e22\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e0a\u0e19\u0e34\u0e14\u0e19\u0e35\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e32\u0e23\u0e1e\u0e34\u0e29 (Toxin) \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1c\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e1a\u0e43\u0e19\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07\u0e44\u0e14\u0e49<\/p>\n<p>&nbsp;<\/p>\n<p>\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e01\u0e34\u0e14\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e40\u0e14\u0e47\u0e01\u0e0a\u0e48\u0e27\u0e07\u0e27\u0e31\u0e22\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e32\u0e22\u0e38 5 &#8211; 15 \u0e1b\u0e35 \u0e2b\u0e23\u0e37\u0e2d \u0e04\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e25\u0e38\u0e01\u0e04\u0e25\u0e35\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07 \u0e21\u0e31\u0e01\u0e44\u0e14\u0e49\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e27\u0e48\u0e32\u0e21\u0e35\u0e1e\u0e35\u0e48\u0e2b\u0e23\u0e37\u0e2d\u0e19\u0e49\u0e2d\u0e07\u0e43\u0e19\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e21\u0e35\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e1a\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19 \u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e23\u0e04\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e41\u0e1e\u0e23\u0e48\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e19\u0e49\u0e33\u0e21\u0e39\u0e01 \u0e19\u0e49\u0e33\u0e25\u0e32\u0e22\u0e17\u0e35\u0e48\u0e44\u0e2d\u0e08\u0e32\u0e21\u0e2d\u0e2d\u0e01\u0e44\u0e1b \u0e41\u0e25\u0e30\u0e08\u0e30\u0e2b\u0e22\u0e38\u0e14\u0e41\u0e1e\u0e23\u0e48\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2b\u0e25\u0e31\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e14\u0e49\u0e27\u0e22\u0e22\u0e32\u0e1b\u0e0f\u0e34\u0e0a\u0e35\u0e27\u0e19\u0e30\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e41\u0e25\u0e49\u0e27 1 \u0e27\u0e31\u0e19<\/p>\n<p>&nbsp;<\/p>\n<h3>\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32<\/h3>\n<p>\u0e04\u0e37\u0e2d \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e22\u0e32\u0e1b\u0e0f\u0e34\u0e0a\u0e35\u0e27\u0e19\u0e30\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e1e\u0e19\u0e19\u0e34\u0e0b\u0e34\u0e25\u0e34\u0e19 (Penicillin) \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e30\u0e21\u0e47\u0e2d\u0e01\u0e0b\u0e35\u0e0b\u0e34\u0e25\u0e25\u0e34\u0e19 (Amoxicillin) \u0e2b\u0e23\u0e37\u0e2d \u0e40\u0e0b\u0e1f\u0e32\u0e42\u0e25\u0e2a\u0e1b\u0e2d\u0e23\u0e34\u0e19 (Cephalosporin) \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e27\u0e25\u0e32 10 \u0e27\u0e31\u0e19 \u0e42\u0e14\u0e22\u0e41\u0e19\u0e30\u0e19\u0e33\u0e43\u0e2b\u0e49\u0e01\u0e34\u0e19\u0e22\u0e32\u0e1b\u0e0f\u0e34\u0e0a\u0e35\u0e27\u0e19\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e23\u0e1a\u0e41\u0e21\u0e49\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e08\u0e30\u0e2b\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e01\u0e15\u0e34\u0e41\u0e25\u0e49\u0e27\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e34\u0e14\u0e20\u0e32\u0e27\u0e30\u0e41\u0e17\u0e23\u0e01\u0e0b\u0e49\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e23\u0e39\u0e21\u0e32\u0e15\u0e34\u0e01 (Rheumatic fever) \u0e0b\u0e36\u0e48\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e25\u0e34\u0e49\u0e19\u0e2b\u0e31\u0e27\u0e43\u0e08\u0e2d\u0e31\u0e01\u0e40\u0e2a\u0e1a\u0e41\u0e25\u0e30\u0e44\u0e15\u0e2d\u0e31\u0e01\u0e40\u0e2a\u0e1a\u0e40\u0e09\u0e35\u0e22\u0e1a\u0e1e\u0e25\u0e31\u0e19 (Acute post-streptococcal glomerulonephritis) \u0e01\u0e23\u0e13\u0e35\u0e17\u0e35\u0e48\u0e41\u0e1e\u0e49\u0e22\u0e32\u0e40\u0e1e\u0e19\u0e19\u0e34\u0e0b\u0e34\u0e25\u0e34\u0e19\u0e41\u0e19\u0e30\u0e19\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e22\u0e32\u0e01\u0e25\u0e38\u0e48\u0e21\u0e41\u0e21\u0e04\u0e42\u0e04\u0e23\u0e44\u0e25\u0e14\u0e4c (Macrolides) \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e35\u0e23\u0e34\u0e42\u0e18\u0e23\u0e21\u0e31\u0e22\u0e0b\u0e34\u0e19 (Erythromycin) \u0e2b\u0e23\u0e37\u0e2d \u0e2d\u0e30\u0e0b\u0e34\u0e42\u0e18\u0e23\u0e21\u0e31\u0e22\u0e0b\u0e34\u0e19 (Azithromycin) \u0e41\u0e17\u0e19<\/p>\n<p>&nbsp;<\/p>\n<p>\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e14\u0e35\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e19\u0e48\u0e32\u0e01\u0e25\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e43\u0e04\u0e23\u0e04\u0e34\u0e14 \u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e21\u0e31\u0e01\u0e21\u0e35\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e44\u0e21\u0e48\u0e23\u0e38\u0e19\u0e41\u0e23\u0e07 \u0e2b\u0e32\u0e01\u0e2a\u0e07\u0e2a\u0e31\u0e22\u0e27\u0e48\u0e32\u0e27\u0e48\u0e32\u0e21\u0e35\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e2a\u0e07\u0e2a\u0e31\u0e22\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07\u0e04\u0e27\u0e23\u0e23\u0e35\u0e1a\u0e1e\u0e32\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e21\u0e32\u0e1e\u0e1a\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e23\u0e27\u0e08\u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e40\u0e23\u0e34\u0e48\u0e21\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e15\u0e48\u0e2d\u0e44\u0e1b<\/p>\n<p>&nbsp;<\/p>\n<p>\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19 \u0e19\u0e2d\u0e01\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e43\u0e19\u0e01\u0e32\u0e23\u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07\u0e41\u0e25\u0e49\u0e27 \u0e22\u0e31\u0e07\u0e21\u0e35\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e17\u0e32\u0e07\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e1c\u0e25\u0e23\u0e27\u0e14\u0e40\u0e23\u0e47\u0e27\u0e20\u0e32\u0e22\u0e43\u0e19 1 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07 \u0e04\u0e37\u0e2d \u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2b\u0e32\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e08\u0e32\u0e01\u0e04\u0e2d\u0e2b\u0e2d\u0e22\u0e41\u0e25\u0e30\u0e17\u0e2d\u0e19\u0e0b\u0e34\u0e25 \u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32 Rapid strep group A test \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e37\u0e19\u0e22\u0e31\u0e19\u0e27\u0e48\u0e32\u0e21\u0e35\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e2a\u0e40\u0e15\u0e23\u0e1b\u0e42\u0e15\u0e04\u0e2d\u0e04\u0e04\u0e31\u0e2a\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e2d \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07 \u0e04\u0e27\u0e23\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e2b\u0e22\u0e38\u0e14\u0e40\u0e23\u0e35\u0e22\u0e19\u0e08\u0e19\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e1b\u0e0f\u0e34\u0e0a\u0e35\u0e27\u0e19\u0e30\u0e41\u0e25\u0e49\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e49\u0e2d\u0e22 1 \u0e27\u0e31\u0e19 \u0e08\u0e36\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e01\u0e25\u0e31\u0e1a\u0e44\u0e1b\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e23\u0e48\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e42\u0e23\u0e04<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>\u0e1e\u0e1a\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07\u0e2a\u0e34\u0e19\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e2a\u0e32\u0e02\u0e32\u0e43\u0e01\u0e25\u0e49\u0e1a\u0e49\u0e32\u0e19\u0e04\u0e38\u0e13 #\u0e04\u0e25\u0e34\u0e4a\u0e01\u0e40\u0e25\u0e22<\/strong><\/em><\/p>\n<p><a href=\"https:\/\/www.synphaet.co.th\/children-ramintra\/schedule\/?clinic=1808\">\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e40\u0e14\u0e47\u0e01\u0e2a\u0e34\u0e19\u0e41\u0e1e\u0e17\u0e22\u0e4c\u00a0\u00a0<\/a><\/p>\n<p><a href=\"https:\/\/bit.ly\/2Cbm0F0\">\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e34\u0e19\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e25\u0e33\u0e25\u0e39\u0e01\u0e01\u0e32\u00a0<\/a><\/p>\n<p><a href=\"https:\/\/bit.ly\/2UNkbUZ\">\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e34\u0e19\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e17\u0e1e\u0e32\u0e23\u0e31\u0e01\u0e29\u0e4c\u00a0<\/a><\/p>\n<p><a href=\"https:\/\/bit.ly\/3fu0IRo\">\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e34\u0e19\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h3><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07 (Scarlet fever) \u0e42\u0e23\u0e04\u0e0a\u0e37\u0e48\u0e2d\u0e44\u0e17\u0e22\u0e46 \u0e17\u0e35\u0e48\u0e43\u0e04\u0e23\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e22\u0e31&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15],"tags":[87],"class_list":["post-539","post","type-post","status-publish","format-standard","hentry","category--th","tag-87"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07 (Scarlet fever) | \u0e23\u0e1e.\u0e40\u0e14\u0e47\u0e01\u0e2a\u0e34\u0e19\u0e41\u0e1e\u0e17\u0e22\u0e4c<\/title>\n<meta name=\"description\" content=\"\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07 (Scarlet fever) \u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23? \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e01\u0e31\u0e1a\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07 \u0e2d\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e20\u0e32\u0e27\u0e30\u0e41\u0e17\u0e23\u0e01\u0e0b\u0e49\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e42\u0e23\u0e04 \u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e01\u0e34\u0e14\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.synphaet.co.th\/children-ramintra\/\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07 (Scarlet fever) | \u0e23\u0e1e.\u0e40\u0e14\u0e47\u0e01\u0e2a\u0e34\u0e19\u0e41\u0e1e\u0e17\u0e22\u0e4c\" \/>\n<meta property=\"og:description\" content=\"\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07 (Scarlet fever) \u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23? \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e01\u0e31\u0e1a\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07 \u0e2d\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e20\u0e32\u0e27\u0e30\u0e41\u0e17\u0e23\u0e01\u0e0b\u0e49\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e42\u0e23\u0e04 \u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e01\u0e34\u0e14\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.synphaet.co.th\/children-ramintra\/\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e23\u0e1e.\u0e40\u0e14\u0e47\u0e01\u0e2a\u0e34\u0e19\u0e41\u0e1e\u0e17\u0e22\u0e4c\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-25T03:00:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-15T02:07:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.synphaet.co.th\\\/children-ramintra\\\/%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b9%84%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%b5%e0%b8%94%e0%b8%b3%e0%b8%ad%e0%b8%b5%e0%b9%81%e0%b8%94%e0%b8%87\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.synphaet.co.th\\\/children-ramintra\\\/%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b9%84%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%b5%e0%b8%94%e0%b8%b3%e0%b8%ad%e0%b8%b5%e0%b9%81%e0%b8%94%e0%b8%87\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07 (Scarlet fever)\",\"datePublished\":\"2019-12-25T03:00:28+00:00\",\"dateModified\":\"2020-07-15T02:07:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.synphaet.co.th\\\/children-ramintra\\\/%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b9%84%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%b5%e0%b8%94%e0%b8%b3%e0%b8%ad%e0%b8%b5%e0%b9%81%e0%b8%94%e0%b8%87\\\/\"},\"wordCount\":41,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.synphaet.co.th\\\/children-ramintra\\\/#organization\"},\"keywords\":[\"\u0e0a\u0e33\u0e19\u0e32\u0e0d\u0e01\u0e32\u0e23\u0e42\u0e23\u0e04\u0e15\u0e34\u0e14\u0e40\u0e0a\u0e37\u0e49\u0e2d\"],\"articleSection\":[\"\u0e42\u0e23\u0e04\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\"],\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.synphaet.co.th\\\/children-ramintra\\\/%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b9%84%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%b5%e0%b8%94%e0%b8%b3%e0%b8%ad%e0%b8%b5%e0%b9%81%e0%b8%94%e0%b8%87\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.synphaet.co.th\\\/children-ramintra\\\/%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b9%84%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%b5%e0%b8%94%e0%b8%b3%e0%b8%ad%e0%b8%b5%e0%b9%81%e0%b8%94%e0%b8%87\\\/\",\"url\":\"https:\\\/\\\/www.synphaet.co.th\\\/children-ramintra\\\/%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b9%84%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%b5%e0%b8%94%e0%b8%b3%e0%b8%ad%e0%b8%b5%e0%b9%81%e0%b8%94%e0%b8%87\\\/\",\"name\":\"\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07 (Scarlet fever) | \u0e23\u0e1e.\u0e40\u0e14\u0e47\u0e01\u0e2a\u0e34\u0e19\u0e41\u0e1e\u0e17\u0e22\u0e4c\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.synphaet.co.th\\\/children-ramintra\\\/#website\"},\"datePublished\":\"2019-12-25T03:00:28+00:00\",\"dateModified\":\"2020-07-15T02:07:25+00:00\",\"description\":\"\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07 (Scarlet fever) \u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23? \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e01\u0e31\u0e1a\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07 \u0e2d\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e20\u0e32\u0e27\u0e30\u0e41\u0e17\u0e23\u0e01\u0e0b\u0e49\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e42\u0e23\u0e04 \u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e01\u0e34\u0e14\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.synphaet.co.th\\\/children-ramintra\\\/%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b9%84%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%b5%e0%b8%94%e0%b8%b3%e0%b8%ad%e0%b8%b5%e0%b9%81%e0%b8%94%e0%b8%87\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.synphaet.co.th\\\/children-ramintra\\\/%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b9%84%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%b5%e0%b8%94%e0%b8%b3%e0%b8%ad%e0%b8%b5%e0%b9%81%e0%b8%94%e0%b8%87\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.synphaet.co.th\\\/children-ramintra\\\/%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b9%84%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%b5%e0%b8%94%e0%b8%b3%e0%b8%ad%e0%b8%b5%e0%b9%81%e0%b8%94%e0%b8%87\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.synphaet.co.th\\\/children-ramintra\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07 (Scarlet fever)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.synphaet.co.th\\\/children-ramintra\\\/#website\",\"url\":\"https:\\\/\\\/www.synphaet.co.th\\\/children-ramintra\\\/\",\"name\":\"\u0e23\u0e1e.\u0e40\u0e14\u0e47\u0e01\u0e2a\u0e34\u0e19\u0e41\u0e1e\u0e17\u0e22\u0e4c\",\"description\":\"\u0e23\u0e1e. \u0e2a\u0e34\u0e19\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e34\u0e21\u0e13\u0e11\u0e25 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2a\u0e32\u0e02\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e19\u0e43\u0e08\\\/\u0e43\u0e01\u0e25\u0e49\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e0a\u0e48\u0e19 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e40\u0e17\u0e1e\u0e32\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e25\u0e33\u0e25\u0e39\u0e01\u0e01\u0e32 \u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e40\u0e2a\u0e23\u0e35\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e41\u0e25\u0e30 \u0e23\u0e1e. \u0e40\u0e14\u0e47\u0e01\u0e2a\u0e34\u0e19\u0e41\u0e1e\u0e17\u0e22\u0e4c\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.synphaet.co.th\\\/children-ramintra\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.synphaet.co.th\\\/children-ramintra\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.synphaet.co.th\\\/children-ramintra\\\/#organization\",\"name\":\"\u0e23\u0e1e.\u0e40\u0e14\u0e47\u0e01\u0e2a\u0e34\u0e19\u0e41\u0e1e\u0e17\u0e22\u0e4c\",\"url\":\"https:\\\/\\\/www.synphaet.co.th\\\/children-ramintra\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.synphaet.co.th\\\/children-ramintra\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.synphaet.co.th\\\/children-ramintra\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2019\\\/11\\\/new-website-kid-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/www.synphaet.co.th\\\/children-ramintra\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2019\\\/11\\\/new-website-kid-logo-1.png\",\"width\":320,\"height\":152,\"caption\":\"\u0e23\u0e1e.\u0e40\u0e14\u0e47\u0e01\u0e2a\u0e34\u0e19\u0e41\u0e1e\u0e17\u0e22\u0e4c\"},\"image\":{\"@id\":\"https:\\\/\\\/www.synphaet.co.th\\\/children-ramintra\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/www.synphaet.co.th\\\/children-ramintra\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07 (Scarlet fever) | \u0e23\u0e1e.\u0e40\u0e14\u0e47\u0e01\u0e2a\u0e34\u0e19\u0e41\u0e1e\u0e17\u0e22\u0e4c","description":"\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07 (Scarlet fever) \u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23? \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e01\u0e31\u0e1a\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07 \u0e2d\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e20\u0e32\u0e27\u0e30\u0e41\u0e17\u0e23\u0e01\u0e0b\u0e49\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e42\u0e23\u0e04 \u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e01\u0e34\u0e14\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.synphaet.co.th\/children-ramintra\/\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07 (Scarlet fever) | \u0e23\u0e1e.\u0e40\u0e14\u0e47\u0e01\u0e2a\u0e34\u0e19\u0e41\u0e1e\u0e17\u0e22\u0e4c","og_description":"\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07 (Scarlet fever) \u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23? \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e01\u0e31\u0e1a\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07 \u0e2d\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e20\u0e32\u0e27\u0e30\u0e41\u0e17\u0e23\u0e01\u0e0b\u0e49\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e42\u0e23\u0e04 \u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e01\u0e34\u0e14\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07","og_url":"https:\/\/www.synphaet.co.th\/children-ramintra\/\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07\/","og_site_name":"\u0e23\u0e1e.\u0e40\u0e14\u0e47\u0e01\u0e2a\u0e34\u0e19\u0e41\u0e1e\u0e17\u0e22\u0e4c","article_published_time":"2019-12-25T03:00:28+00:00","article_modified_time":"2020-07-15T02:07:25+00:00","twitter_card":"summary_large_image","twitter_misc":{"Written by":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.synphaet.co.th\/children-ramintra\/%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b9%84%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%b5%e0%b8%94%e0%b8%b3%e0%b8%ad%e0%b8%b5%e0%b9%81%e0%b8%94%e0%b8%87\/#article","isPartOf":{"@id":"https:\/\/www.synphaet.co.th\/children-ramintra\/%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b9%84%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%b5%e0%b8%94%e0%b8%b3%e0%b8%ad%e0%b8%b5%e0%b9%81%e0%b8%94%e0%b8%87\/"},"author":{"name":"","@id":""},"headline":"\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07 (Scarlet fever)","datePublished":"2019-12-25T03:00:28+00:00","dateModified":"2020-07-15T02:07:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.synphaet.co.th\/children-ramintra\/%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b9%84%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%b5%e0%b8%94%e0%b8%b3%e0%b8%ad%e0%b8%b5%e0%b9%81%e0%b8%94%e0%b8%87\/"},"wordCount":41,"commentCount":0,"publisher":{"@id":"https:\/\/www.synphaet.co.th\/children-ramintra\/#organization"},"keywords":["\u0e0a\u0e33\u0e19\u0e32\u0e0d\u0e01\u0e32\u0e23\u0e42\u0e23\u0e04\u0e15\u0e34\u0e14\u0e40\u0e0a\u0e37\u0e49\u0e2d"],"articleSection":["\u0e42\u0e23\u0e04\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32"],"inLanguage":"th","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.synphaet.co.th\/children-ramintra\/%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b9%84%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%b5%e0%b8%94%e0%b8%b3%e0%b8%ad%e0%b8%b5%e0%b9%81%e0%b8%94%e0%b8%87\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.synphaet.co.th\/children-ramintra\/%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b9%84%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%b5%e0%b8%94%e0%b8%b3%e0%b8%ad%e0%b8%b5%e0%b9%81%e0%b8%94%e0%b8%87\/","url":"https:\/\/www.synphaet.co.th\/children-ramintra\/%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b9%84%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%b5%e0%b8%94%e0%b8%b3%e0%b8%ad%e0%b8%b5%e0%b9%81%e0%b8%94%e0%b8%87\/","name":"\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07 (Scarlet fever) | \u0e23\u0e1e.\u0e40\u0e14\u0e47\u0e01\u0e2a\u0e34\u0e19\u0e41\u0e1e\u0e17\u0e22\u0e4c","isPartOf":{"@id":"https:\/\/www.synphaet.co.th\/children-ramintra\/#website"},"datePublished":"2019-12-25T03:00:28+00:00","dateModified":"2020-07-15T02:07:25+00:00","description":"\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07 (Scarlet fever) \u0e04\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23? \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e01\u0e31\u0e1a\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07 \u0e2d\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e20\u0e32\u0e27\u0e30\u0e41\u0e17\u0e23\u0e01\u0e0b\u0e49\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e42\u0e23\u0e04 \u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e01\u0e34\u0e14\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07","breadcrumb":{"@id":"https:\/\/www.synphaet.co.th\/children-ramintra\/%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b9%84%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%b5%e0%b8%94%e0%b8%b3%e0%b8%ad%e0%b8%b5%e0%b9%81%e0%b8%94%e0%b8%87\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.synphaet.co.th\/children-ramintra\/%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b9%84%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%b5%e0%b8%94%e0%b8%b3%e0%b8%ad%e0%b8%b5%e0%b9%81%e0%b8%94%e0%b8%87\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.synphaet.co.th\/children-ramintra\/%e0%b9%82%e0%b8%a3%e0%b8%84%e0%b9%84%e0%b8%82%e0%b9%89%e0%b8%ad%e0%b8%b5%e0%b8%94%e0%b8%b3%e0%b8%ad%e0%b8%b5%e0%b9%81%e0%b8%94%e0%b8%87\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.synphaet.co.th\/children-ramintra\/"},{"@type":"ListItem","position":2,"name":"\u0e42\u0e23\u0e04\u0e44\u0e02\u0e49\u0e2d\u0e35\u0e14\u0e33\u0e2d\u0e35\u0e41\u0e14\u0e07 (Scarlet fever)"}]},{"@type":"WebSite","@id":"https:\/\/www.synphaet.co.th\/children-ramintra\/#website","url":"https:\/\/www.synphaet.co.th\/children-ramintra\/","name":"\u0e23\u0e1e.\u0e40\u0e14\u0e47\u0e01\u0e2a\u0e34\u0e19\u0e41\u0e1e\u0e17\u0e22\u0e4c","description":"\u0e23\u0e1e. \u0e2a\u0e34\u0e19\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e34\u0e21\u0e13\u0e11\u0e25 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2a\u0e32\u0e02\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e19\u0e43\u0e08\/\u0e43\u0e01\u0e25\u0e49\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e0a\u0e48\u0e19 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e40\u0e17\u0e1e\u0e32\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e25\u0e33\u0e25\u0e39\u0e01\u0e01\u0e32 \u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e40\u0e2a\u0e23\u0e35\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e41\u0e25\u0e30 \u0e23\u0e1e. \u0e40\u0e14\u0e47\u0e01\u0e2a\u0e34\u0e19\u0e41\u0e1e\u0e17\u0e22\u0e4c","publisher":{"@id":"https:\/\/www.synphaet.co.th\/children-ramintra\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.synphaet.co.th\/children-ramintra\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/www.synphaet.co.th\/children-ramintra\/#organization","name":"\u0e23\u0e1e.\u0e40\u0e14\u0e47\u0e01\u0e2a\u0e34\u0e19\u0e41\u0e1e\u0e17\u0e22\u0e4c","url":"https:\/\/www.synphaet.co.th\/children-ramintra\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.synphaet.co.th\/children-ramintra\/#\/schema\/logo\/image\/","url":"https:\/\/www.synphaet.co.th\/children-ramintra\/wp-content\/uploads\/sites\/3\/2019\/11\/new-website-kid-logo-1.png","contentUrl":"https:\/\/www.synphaet.co.th\/children-ramintra\/wp-content\/uploads\/sites\/3\/2019\/11\/new-website-kid-logo-1.png","width":320,"height":152,"caption":"\u0e23\u0e1e.\u0e40\u0e14\u0e47\u0e01\u0e2a\u0e34\u0e19\u0e41\u0e1e\u0e17\u0e22\u0e4c"},"image":{"@id":"https:\/\/www.synphaet.co.th\/children-ramintra\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/www.synphaet.co.th\/children-ramintra\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/www.synphaet.co.th\/children-ramintra\/wp-json\/wp\/v2\/posts\/539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.synphaet.co.th\/children-ramintra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.synphaet.co.th\/children-ramintra\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.synphaet.co.th\/children-ramintra\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.synphaet.co.th\/children-ramintra\/wp-json\/wp\/v2\/comments?post=539"}],"version-history":[{"count":9,"href":"https:\/\/www.synphaet.co.th\/children-ramintra\/wp-json\/wp\/v2\/posts\/539\/revisions"}],"predecessor-version":[{"id":3557,"href":"https:\/\/www.synphaet.co.th\/children-ramintra\/wp-json\/wp\/v2\/posts\/539\/revisions\/3557"}],"wp:attachment":[{"href":"https:\/\/www.synphaet.co.th\/children-ramintra\/wp-json\/wp\/v2\/media?parent=539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.synphaet.co.th\/children-ramintra\/wp-json\/wp\/v2\/categories?post=539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.synphaet.co.th\/children-ramintra\/wp-json\/wp\/v2\/tags?post=539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}